{"id":7714,"date":"2026-03-27T20:34:01","date_gmt":"2026-03-27T19:34:01","guid":{"rendered":"https:\/\/ontaneda.loginmkt.com.ec\/?page_id=7714"},"modified":"2026-04-15T22:07:58","modified_gmt":"2026-04-15T20:07:58","slug":"propiedad-intelectual","status":"publish","type":"page","link":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/","title":{"rendered":"Intellectual Property"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7714","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"Lg1FT4RRzQ4vE0f1jGDHLpaO4Nd0WdGnoVLoOuAaB8Y\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ontaneda &amp; Posso -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Propiedad Intelectual - Ontaneda &amp; Posso\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ontaneda-posso.com\/wp-content\/uploads\/2026\/03\/Logo-Web-3.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ontaneda-posso.com\/wp-content\/uploads\/2026\/03\/Logo-Web-3.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"220\" \/>\n\t\t<meta property=\"og:image:height\" content=\"83\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-27T19:34:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-15T20:07:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Propiedad Intelectual - Ontaneda &amp; Posso\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ontaneda-posso.com\/wp-content\/uploads\/2026\/03\/Logo-Web-3.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/#listItem\",\"name\":\"Propiedad Intelectual\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/#listItem\",\"position\":2,\"name\":\"Propiedad Intelectual\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/#organization\",\"name\":\"Ontaneda & Posso\",\"url\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/\",\"telephone\":\"+593962793459\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ontaneda-posso.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-Web-3.png\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/#organizationLogo\",\"width\":220,\"height\":83},\"image\":{\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ontaneda-posso\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/#webpage\",\"url\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/\",\"name\":\"Propiedad Intelectual - Ontaneda & Posso\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/propiedad-intelectual\\\/#breadcrumblist\"},\"datePublished\":\"2026-03-27T20:34:01+01:00\",\"dateModified\":\"2026-04-15T22:07:58+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/\",\"name\":\"Ontaneda & Posso\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ontaneda-posso.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Propiedad Intelectual - Ontaneda & Posso","description":"","canonical_url":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"Lg1FT4RRzQ4vE0f1jGDHLpaO4Nd0WdGnoVLoOuAaB8Y","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ontaneda-posso.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ontaneda-posso.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/#listItem","name":"Propiedad Intelectual"}},{"@type":"ListItem","@id":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/#listItem","position":2,"name":"Propiedad Intelectual","previousItem":{"@type":"ListItem","@id":"https:\/\/ontaneda-posso.com\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/ontaneda-posso.com\/en\/#organization","name":"Ontaneda & Posso","url":"https:\/\/ontaneda-posso.com\/en\/","telephone":"+593962793459","logo":{"@type":"ImageObject","url":"https:\/\/ontaneda-posso.com\/wp-content\/uploads\/2026\/03\/Logo-Web-3.png","@id":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/#organizationLogo","width":220,"height":83},"image":{"@id":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/company\/ontaneda-posso\/"]},{"@type":"WebPage","@id":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/#webpage","url":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/","name":"Propiedad Intelectual - Ontaneda & Posso","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ontaneda-posso.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/#breadcrumblist"},"datePublished":"2026-03-27T20:34:01+01:00","dateModified":"2026-04-15T22:07:58+02:00"},{"@type":"WebSite","@id":"https:\/\/ontaneda-posso.com\/en\/#website","url":"https:\/\/ontaneda-posso.com\/en\/","name":"Ontaneda & Posso","inLanguage":"en-US","publisher":{"@id":"https:\/\/ontaneda-posso.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ontaneda &amp; Posso -","og:type":"article","og:title":"Propiedad Intelectual - Ontaneda &amp; Posso","og:url":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/","og:image":"https:\/\/ontaneda-posso.com\/wp-content\/uploads\/2026\/03\/Logo-Web-3.png","og:image:secure_url":"https:\/\/ontaneda-posso.com\/wp-content\/uploads\/2026\/03\/Logo-Web-3.png","og:image:width":220,"og:image:height":83,"article:published_time":"2026-03-27T19:34:01+00:00","article:modified_time":"2026-04-15T20:07:58+00:00","twitter:card":"summary_large_image","twitter:title":"Propiedad Intelectual - Ontaneda &amp; Posso","twitter:image":"https:\/\/ontaneda-posso.com\/wp-content\/uploads\/2026\/03\/Logo-Web-3.png"},"aioseo_meta_data":{"post_id":"7714","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-04-15 14:00:03","updated":"2026-04-15 20:29:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ontaneda-posso.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPropiedad Intelectual\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ontaneda-posso.com\/en"},{"label":"Propiedad Intelectual","link":"https:\/\/ontaneda-posso.com\/en\/propiedad-intelectual\/"}],"_links":{"self":[{"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/pages\/7714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/comments?post=7714"}],"version-history":[{"count":5,"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/pages\/7714\/revisions"}],"predecessor-version":[{"id":7857,"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/pages\/7714\/revisions\/7857"}],"wp:attachment":[{"href":"https:\/\/ontaneda-posso.com\/en\/wp-json\/wp\/v2\/media?parent=7714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}